{"id":7984,"date":"2018-02-02T09:09:34","date_gmt":"2018-02-02T09:09:34","guid":{"rendered":"http:\/\/cio.edu.umh.es\/?p=7984"},"modified":"2018-02-02T09:09:34","modified_gmt":"2018-02-02T09:09:34","slug":"curso-estimacion-en-areas-pequenas","status":"publish","type":"post","link":"https:\/\/cio.umh.es\/en\/2018\/02\/02\/curso-estimacion-en-areas-pequenas\/","title":{"rendered":"Curso &#034;Estimaci\u00f3n en \u00c1reas Peque\u00f1as&#034;"},"content":{"rendered":"<p>[:es]<span style=\"color: #000000\">El Prof. Domingo Morales del CIO impartir\u00e1 un curso de \u201cEstimaci\u00f3n en \u00c1reas Peque\u00f1as\u201d en el Instituto Nacional de Estad\u00edsticas y Censos de Ecuador (INEC). Este curso servir\u00e1 para asesorar a los alumnos del mismo en la realizaci\u00f3n de un trabajo, aplicado a datos de la estad\u00edstica p\u00fablica de Ecuador.<\/span><br \/>\n<span style=\"color: #000000\">El curso tendr\u00e1 18 horas lectivas presenciales, impartidas en cuatro d\u00edas, conteniendo sesiones con descripciones metodol\u00f3gicas de car\u00e1cter te\u00f3rico y sesiones aplicadas usando el lenguaje de programaci\u00f3n R. Como parte del curso, los alumnos recibir\u00e1n asesoramiento mediante tutor\u00edas v\u00eda internet, para la realizaci\u00f3n de un trabajo de aplicaci\u00f3n de t\u00e9cnicas de estimaci\u00f3n en \u00e1reas peque\u00f1as a indicadores demogr\u00e1ficos, salud o nutrici\u00f3n a partir de la encuesta de condiciones de vida de Ecuador u otras. Se incluyen demostraciones de las t\u00e9cnicas de estimaci\u00f3n en \u00e1reas peque\u00f1as a personal del INEC.<\/span><br \/>\n<span style=\"color: #000000\">Las fechas exactas del curso de \u00abEstimaci\u00f3n en \u00c1reas Peque\u00f1as\u00bb en el Instituto Nacional de Estad\u00edsticas y Censos de Ecuador en Quito son del <strong>6 al 9 de marzo (4 d\u00edas).<\/strong><\/span>[:]<\/p>","protected":false},"excerpt":{"rendered":"<p>[:es]El Prof. Domingo Morales del CIO impartir\u00e1 un curso de \u201cEstimaci\u00f3n en \u00c1reas Peque\u00f1as\u201d en el Instituto Nacional de Estad\u00edsticas y Censos de Ecuador (INEC). Este curso servir\u00e1 para asesorar a los alumnos del mismo en la realizaci\u00f3n de un trabajo, aplicado a datos de la estad\u00edstica p\u00fablica de Ecuador.<br \/>\nEl curso tendr\u00e1 18 horas lectivas [&#8230;]<\/p>","protected":false},"author":3477,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[873],"tags":[],"_links":{"self":[{"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/posts\/7984"}],"collection":[{"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/users\/3477"}],"replies":[{"embeddable":true,"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/comments?post=7984"}],"version-history":[{"count":0,"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/posts\/7984\/revisions"}],"wp:attachment":[{"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/media?parent=7984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/categories?post=7984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cio.umh.es\/en\/wp-json\/wp\/v2\/tags?post=7984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}